{"id":11178,"date":"2025-09-04T16:59:59","date_gmt":"2025-09-04T14:59:59","guid":{"rendered":"https:\/\/www.trendgames.de\/blog\/?p=11178"},"modified":"2025-09-04T17:00:01","modified_gmt":"2025-09-04T15:00:01","slug":"cobi-printkatalog-2025-2-zur-bestellung-erhalten","status":"publish","type":"post","link":"https:\/\/www.trendgames.de\/blog\/cobi-printkatalog-2025-2-zur-bestellung-erhalten\/","title":{"rendered":"COBI Printkatalog 2025\/2 zur Bestellung erhalten"},"content":{"rendered":"<div class=\"twttr_buttons\"><div class=\"twttr_twitter\">\n\t\t\t\t\t<a href=\"http:\/\/twitter.com\/share?text=COBI+Printkatalog+2025%2F2+zur+Bestellung+erhalten\" class=\"twitter-share-button\" data-via=\"\" data-hashtags=\"\"  data-size=\"default\" data-url=\"https:\/\/www.trendgames.de\/blog\/cobi-printkatalog-2025-2-zur-bestellung-erhalten\/\"  data-related=\"\" target=\"_blank\">Tweet<\/a>\n\t\t\t\t<\/div><div class=\"twttr_followme\">\n\t\t\t\t\t\t<a href=\"https:\/\/twitter.com\/@TrendgamesBlog\" class=\"twitter-follow-button\" data-show-count=\"false\" data-size=\"default\"  data-show-screen-name=\"false\"  target=\"_blank\">Follow me<\/a>\n\t\t\t\t\t<\/div><\/div>\n<p>Mit der heutigen Lieferung sind ebenfalls zahlreiche COBI Kataloge der aktuellen Ausgabe 2025\/2 Europa mitgekommen.<\/p>\n\n\n\n<h4>Bedingungen f\u00fcr den Erhalt <\/h4>\n\n\n\n<p>Den COBI Katalog legen wir bei, wenn ihr mindestens einen COBI Artikel bei uns bestellt. Hierbei muss es sich um lagernde, also vorr\u00e4tige Sets handeln. Vorbestellungen werden erst ausgeliefert werden, wenn das Produkt erschienen ist. Daher k\u00f6nnen wir nicht garantieren, dass wir zu diesem Zeitpunkt noch Kataloge vorr\u00e4tig haben.<\/p>\n\n\n\n<p>Zwar haben wir viele Printkataloge erhalten, dennoch gilt: Nur, solange der Vorrat reicht. <\/p>\n\n\n\n<p>Tats\u00e4chlich ist es das erste Mal in diesem Jahr, dass wir mehr als zwei bis drei Kataloge erhalten haben, sodass wir diese der Bestellung beilegen k\u00f6nnen.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.steine-kanal.de\/wp-content\/uploads\/kataloge\/cobi-2025-2-consumer-catalogue.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Eine PDF-Version des Katalogs erhaltet ihr hier<\/a><\/strong>.<\/p>\n\n\n\n<h4>Weitere Neuheiten vorr\u00e4tig <\/h4>\n\n\n\n<p>Das August-Highlight, die Su-57 (5909) wurde an uns ausgeliefert und an alle Vorbesteller verschickt. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"576\" src=\"https:\/\/www.trendgames.de\/blog\/wp-content\/uploads\/2025\/09\/5909-5.jpg\" alt=\"COBI 5909 Su-57 Felon\" class=\"wp-image-11199\" srcset=\"https:\/\/www.trendgames.de\/blog\/wp-content\/uploads\/2025\/09\/5909-5.jpg 800w, https:\/\/www.trendgames.de\/blog\/wp-content\/uploads\/2025\/09\/5909-5-300x216.jpg 300w, https:\/\/www.trendgames.de\/blog\/wp-content\/uploads\/2025\/09\/5909-5-768x553.jpg 768w, https:\/\/www.trendgames.de\/blog\/wp-content\/uploads\/2025\/09\/5909-5-230x166.jpg 230w, https:\/\/www.trendgames.de\/blog\/wp-content\/uploads\/2025\/09\/5909-5-350x252.jpg 350w, https:\/\/www.trendgames.de\/blog\/wp-content\/uploads\/2025\/09\/5909-5-480x346.jpg 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Da unsere bestellte Anzahl bereits vergriffen ist, bestellt das Set gern in unserem <a rel=\"noreferrer noopener\" href=\"https:\/\/www.trendgames.de\/Vorbestellungen\/COBI-5909-Su-57-Felon::1003.html\" target=\"_blank\">Onlineshop<\/a> und lasst euch f\u00fcr die n\u00e4chste Lieferung vormerken. Diese wird direkt <a rel=\"noreferrer noopener\" href=\"https:\/\/www.trendgames.de\/blog\/trendgames-familie-macht-urlaub\/\" target=\"_blank\">nach unserem Urlaub eintreffen<\/a>.<\/p>\n\n\n\n<p>Vorr\u00e4tig sind folgende Sets:<\/p>\n\n\n\n<ul>\n<li><a href=\"https:\/\/www.trendgames.de\/Vorbestellungen\/COBI-2661-Light-Tank-7TP::1006.html\" target=\"_blank\" rel=\"noreferrer noopener\">COBI 2661 7TP Light Tank<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.trendgames.de\/Vorbestellungen\/COBI-24626-Citroen-Type-H-1947-1981-Holidays::909.html\" target=\"_blank\" rel=\"noreferrer noopener\">COBI 24626 Citro\u00ebn Type H Holidays<\/a><\/li>\n\n\n\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.trendgames.de\/Vorbestellungen\/COBI-20073-Roman-Auxilia::945.html\" target=\"_blank\">COBI 20073 Roman Auxilia<\/a><\/li>\n<\/ul>\n\n\n\n<p>Zum letzten Set, dem Minifigurenset der Imperium Romanum Serie lest ihr demn\u00e4chst ein ausf\u00fchrliches Review auf unserem <a rel=\"noreferrer noopener\" href=\"https:\/\/www.steine-kanal.de\/\" target=\"_blank\">Steine Kanal Blog.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ab sofort erhaltet ihr zu jeder COBI-Bestellung den aktuellen COBI Printkatalog 2025\/2 Europa.<\/p>\n","protected":false},"author":3,"featured_media":11206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,382],"tags":[378,484,737],"_links":{"self":[{"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/posts\/11178"}],"collection":[{"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/comments?post=11178"}],"version-history":[{"count":23,"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/posts\/11178\/revisions"}],"predecessor-version":[{"id":11211,"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/posts\/11178\/revisions\/11211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/media\/11206"}],"wp:attachment":[{"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/media?parent=11178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/categories?post=11178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trendgames.de\/blog\/wp-json\/wp\/v2\/tags?post=11178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}